{"id":2060,"date":"2011-10-16T22:11:13","date_gmt":"2011-10-16T20:11:13","guid":{"rendered":"http:\/\/dahofficial.com\/wordpress\/?p=2060"},"modified":"2011-10-20T01:58:57","modified_gmt":"2011-10-19T23:58:57","slug":"2060","status":"publish","type":"post","link":"https:\/\/dahofficial.com\/wordpress\/2011\/10\/2060\/","title":{"rendered":"\u00ab Monsieur Daho \u00bb et les 4 albums r\u00e9\u00e9dit\u00e9s pour le 31 octobre 2011 dont Pop Satori"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/dahofficial.com\/wordpress\/wp-content\/uploads\/2011\/10\/PopSatori2011_560x560.jpg\" alt=\"Etienne Daho - Pop Satori - R\u00e9\u00e9dition 2011\" \/><br \/>\n<br \/>\nLe v\u00e9ritable \u00e9lan de la carri\u00e8re d\u2019Etienne fut pris avec Le Grand Sommeil, Weekend \u00e0 Rome et l\u2019album La Notte La notte en 1984.<br \/>\nPuis ce fut carr\u00e9ment un envol au cours de l\u2019\u00e9t\u00e9 85 avec le maxi Tomb\u00e9 pour la France et, dans la foul\u00e9e, l\u2019album Pop Satori enregistr\u00e9 entre Londres et Paris qui consacrera en 1986 Daho comme chef de file d\u2019un h\u00e9donisme \u00e9lectro-pop \u00e0 la Fran\u00e7aise.<br \/>\nLa version augment\u00e9e de l\u2019album, avec l\u00e0 encore des d\u00e9mos, des remixes et un des fameux concerts de l\u2019Olympia 86, point d\u2019orgue de la Dahomania, donne pleinement la mesure de ce vent d\u2019euphorie et de folie qui parcourra alors la carri\u00e8re de Daho avec la force d\u2019un cyclone. Inutile d\u2019y revenir, c\u2019est dans tous les livres d\u2019histoire de la France musicale des vingt-cinq derni\u00e8res ann\u00e9es.<\/p>\n<p><strong>Christophe Conte<\/strong><br \/>\n<\/p>\n<h2>Pop Satori<\/h2>\n<p><strong><q> Deluxe Remastered (1985-1987)<\/q><\/strong><br \/>\nExiste en version CD Deluxe et vinyle remasteris\u00e9s (avec coupon pour t\u00e9l\u00e9charger gratuitement l&rsquo;album).<br \/>\n<em>Double CD 39 titres dont 27 bonus<\/em><\/p>\n<h3>Pop Face : Pop Satori album original et bonus<\/h3>\n<p>1. Satori th\u00e8me (Remasteris\u00e9 en 2006)<br \/>\n2. Epaule tattoo (Remasteris\u00e9 en 2006)<br \/>\n3. Paris Le Flore (Remasteris\u00e9 en 2006)<br \/>\n4. Pop \u00e9g\u00e9rie O. (Avec la participation d&rsquo;Elli Medeiros, Remasteris\u00e9 en 2006)<br \/>\n5. Quelqu&rsquo;un qui m&rsquo;ressemble (Remasteris\u00e9 en 2006)<br \/>\n6. Tomb\u00e9 pour la France (Remasteris\u00e9 en 2006)<br \/>\n7. 4000 ann\u00e9es d&rsquo;horreur (Remasteris\u00e9 en 2006)<br \/>\n8. (Qui sera) demain mieux que moi (Remasteris\u00e9 en 2006)<br \/>\n9. Pari \u00e0 l&rsquo;h\u00f4tel (Remasteris\u00e9 en 2006)<br \/>\n10. Duel au soleil (Remasteris\u00e9 en 2006)<br \/>\n11. Satori pop century (Remasteris\u00e9 en 2006)<br \/>\n12. Late night (Remasteris\u00e9 en 2006)<br \/>\n13. Satori th\u00e8me (version \u00ab\u00a0Jack in Paris\u00a0\u00bb) (Remasteris\u00e9 en 2006)<br \/>\n14. Epaule tattoo (extended version) (Remasteris\u00e9 en 2006)<br \/>\n15. Epaule Tattoo (William Orbit&rsquo;s remix) (Remasteris\u00e9 en 2006)<br \/>\n16. Tomb\u00e9 pour la France (Fischerspooner&rsquo;s remix)<br \/>\n17. (Qui sera) demain mieux que moi (Rico Conning&rsquo;s single mix)<br \/>\n18. Duel au soleil (extended version)<br \/>\n19. Duello al sole<\/p>\n<h3>Satori Face :  Satori Tour (The Pop Satori Show)<\/h3>\n<p><em> demos perdues et bonus<\/em><br \/>\n1. Satori theme (Live 1986)<br \/>\n2. Epaule tattoo (Live 1986)<br \/>\n3. 4000 ann\u00e9es d&rsquo;horreur (Live 1986)<br \/>\n4. Paris Le Flore (Live 1986)<br \/>\n5. Quelqu&rsquo;un qui m&rsquo;ressemble (Live 1986)<br \/>\n6. Pop \u00e9g\u00e9rie O. (Avec la participation d&rsquo;Elli Medeiros, Live 1986)<br \/>\n7. (Qui sera) demain mieux que moi (Live 1986)<br \/>\n8. Duel au soleil (Live 1986)<br \/>\n9. Tomb\u00e9 pour la France (Live 1986)<br \/>\n10. Satori pop century (Live 1986)<br \/>\n11. Late night (Live 1986)<br \/>\n12. So In Love (Orchestral Manoeuvres in the Dark featuring Etienne Daho)<br \/>\n13. Sweeter Than You (Remasteris\u00e9 en 2006)<br \/>\n14. Soleil de minuit (Sombre romance mix)<br \/>\n15. Soleil de minuit (Graine de violence mix)<br \/>\n16. Satori pop century (d\u00e9mo 1986)<br \/>\n17. Love at first sight (d\u00e9mo 1986)<br \/>\n18. (Qui sera) demain mieux que moi (d\u00e9mo 1986)<br \/>\n19. Quelqu&rsquo;un qui m&rsquo;ressemble (d\u00e9mo 1986)<br \/>\n20. Centerfold romance (d\u00e9mo 1986)<\/p>\n<p>En parall\u00e8le \u00e0 ces quatre r\u00e9\u00e9ditions sort une double compilation  voulue comme un v\u00e9ritable parcours intime en 40 titres, dont de  nombreuses raret\u00e9s, choisis avec minutie par Etienne en personne. Son  titre : Monsieur Daho. C\u2019\u00e9tait bien la moindre des choses.<br \/>\nChristophe Conte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le v\u00e9ritable \u00e9lan de la carri\u00e8re d\u2019Etienne fut pris avec Le Grand Sommeil, Weekend \u00e0 Rome et l\u2019album La Notte La notte en 1984. Puis ce fut carr\u00e9ment un envol au cours de l\u2019\u00e9t\u00e9 85 avec le maxi Tomb\u00e9 pour la France et, dans la foul\u00e9e, l\u2019album Pop Satori enregistr\u00e9 entre Londres et Paris qui [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9,3],"tags":[],"_links":{"self":[{"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/posts\/2060"}],"collection":[{"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/comments?post=2060"}],"version-history":[{"count":13,"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/posts\/2060\/revisions"}],"predecessor-version":[{"id":11288,"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/posts\/2060\/revisions\/11288"}],"wp:attachment":[{"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/media?parent=2060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/categories?post=2060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/tags?post=2060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}