{"id":6801,"date":"2016-09-27T19:19:18","date_gmt":"2016-09-27T17:19:18","guid":{"rendered":"http:\/\/dahofficial.com\/wordpress\/?p=6801"},"modified":"2016-09-27T19:20:09","modified_gmt":"2016-09-27T17:20:09","slug":"etoiles-et-revers-par-dani","status":"publish","type":"post","link":"http:\/\/dahofficial.com\/wordpress\/2016\/09\/etoiles-et-revers-par-dani\/","title":{"rendered":"ETOILES ET REVERS PAR DANI"},"content":{"rendered":"<p>Publi\u00e9 le 27 septembre 2016<\/p>\n<p>Le single de Dani <q>Etoiles et revers<\/q> r\u00e9alis\u00e9 et \u00e9crit par Etienne a \u00e9t\u00e9 clipp\u00e9 par Antoine Carlier.<br \/>\nC\u2019est la magnifique et saisissante de ressemblance Lou Lesage qui incarne Dani.<br \/>\nCe single annonce la sortie d\u2019une compilation et d\u2019une autobiographie \u00e0 paraitre le 14 octobre 2016.<br \/>\n&#8211; La nuit ne dure pas (Compilation 18 titres) chez Fontana \/ Universal<br \/>\n&#8211; La nuit ne dure pas (Autobiographie) chez Flammarion<br \/>\n<\/br><br \/>\n<img decoding=\"async\" class=\"alignnone size-full wp-image-3980\" title=\"Etoiles er revers - Dani - Etienne Daho\" src=\"http:\/\/dahofficial.com\/wordpress\/wp-content\/themes\/dahofficial\/discographie\/les_chansons_de_linnocence_retrouvee\/images\/20161014_LaNuitNeDurePas_Dani_560\" alt=\"\" width=\"560\" \/><\/br>.<\/br><\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/myIpEu96u48\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p><\/br><\/br><\/br><\/br><\/br><\/br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publi\u00e9 le 27 septembre 2016 Le single de Dani Etoiles et revers r\u00e9alis\u00e9 et \u00e9crit par Etienne a \u00e9t\u00e9 clipp\u00e9 par Antoine Carlier. C\u2019est la magnifique et saisissante de ressemblance Lou Lesage qui incarne Dani. Ce single annonce la sortie d\u2019une compilation et d\u2019une autobiographie \u00e0 paraitre le 14 octobre 2016. &#8211; La nuit ne [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3],"tags":[],"_links":{"self":[{"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/posts\/6801"}],"collection":[{"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/comments?post=6801"}],"version-history":[{"count":2,"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/posts\/6801\/revisions"}],"predecessor-version":[{"id":6803,"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/posts\/6801\/revisions\/6803"}],"wp:attachment":[{"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/media?parent=6801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/categories?post=6801"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/dahofficial.com\/wordpress\/wp-json\/wp\/v2\/tags?post=6801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}